{"id":513,"date":"2024-04-05T13:02:47","date_gmt":"2024-04-05T11:02:47","guid":{"rendered":"https:\/\/www.secretvillage.it\/blog\/?p=513"},"modified":"2024-11-05T12:56:52","modified_gmt":"2024-11-05T11:56:52","slug":"roccascalegna-citta-del-miele","status":"publish","type":"post","link":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/","title":{"rendered":"Roccascalegna citt\u00e0 del miele"},"content":{"rendered":"\n<p><strong>Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca<\/strong>. Il <a href=\"https:\/\/www.secretvillage.it\/comuni\/roccascalegna\" target=\"_blank\" rel=\"noreferrer noopener\">borgo abruzzese<\/a> \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, un crogiolo di storia raccontata dalle architetture della citt\u00e0 vecchia, su cui vegliarda si erge <a href=\"https:\/\/www.secretvillage.it\/segreti\/roccascalegna\/la-rocca\" target=\"_blank\" rel=\"noreferrer noopener\">La Rocca<\/a>. L\u2019imponente fortilizio eretto su di un promontorio roccioso ispira fierezza, resiste al tempo e racchiude in s\u00e9 secoli di trasformazioni della zona, l\u2019<strong><a href=\"https:\/\/www.secretvillage.it\/luoghi\/aventino-medio-sangro?_gl=1*2x6onq*_up*MQ..*_ga*MTg1NzgwODE0NS4xNzIyOTQ4NDIy*_ga_DE4P3C1RSR*MTcyMjk0ODQyMS4xLjEuMTcyMjk0ODQyNS4wLjAuMA..\" target=\"_blank\" rel=\"noreferrer noopener\">Aventino \u2013 Medio Sangro<\/a><\/strong>, cos\u00ec denominata per la congiunzione tra i due fiumi e che al tempo fu una delle comunit\u00e0 montane.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-roccascalegna-tra-le-citta-del-miele\">Roccascalegna tra <a href=\"https:\/\/www.secretvillage.it\/segreti\/roccascalegna\/roccascalegna-citt-del-miele\" target=\"_blank\" rel=\"noreferrer noopener\">Le Citt\u00e0 del Miele<\/a><\/h2>\n\n\n\n<p>Le Citt\u00e0 del Miele sono realt\u00e0 che producono il delizioso alimento e che fanno parte della omonima e nota rete che mira a far emergere l\u2019identit\u00e0 dei paesi italiani e dare il giusto risalto alle tradizioni. Attraverso una agenda annuale di eventi, l\u2019<strong><a href=\"https:\/\/www.cittadelmiele.it\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Associazione Nazionale Le citt\u00e0 del Miele<\/a><\/strong> prende per mano le persone e le conduce verso una finestra aperta, che guarda agli usi e all\u2019apicoltura.<br>Roccascalegna, medievale borgo dalle meravigliose strutture antiche, \u00e8 uno dei comuni che ha abbracciato l\u2019ideale di promozione della propria unicit\u00e0, passando per una delle attivit\u00e0 che lo contraddistinguono: la <strong>mielicoltura<\/strong>.<br>Passeggiando nel dedalo di vie che compone la parte pi\u00f9 risalente di <strong>Roccascalegna<\/strong>, i profumi sanno avvolgere e i luoghi dove ristorarsi di certo non mancano. Botteghe dal fascino artigiano e d\u2019altri tempi si incontrano per le strade, i sapori d\u2019Abruzzo sono godibili e non lasciano insoddisfatti.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-il-miele\">Il miele<\/h3>\n\n\n\n<p>Il <strong>miele<\/strong> in Italia conta una variet\u00e0 molto ampia di tipologie, ognuna con un suo distintivo sapore, suddiviso in regioni e localit\u00e0, e sempre oggetto di maggiore interesse culturale.<br>E\u2019 indicato nelle diete (entro i limiti dettati dalla composizione zuccherina), il <strong>miele \u00e8 salutare<\/strong> e sostituisce lo zucchero come dolcificante; energetico, soddisfa il fabbisogno calorico e in dosi non eccessive, \u00e8 un buon alleato del nutrimento quotidiano.<br>Uno degli abbinamenti che <a href=\"https:\/\/www.micheledimaurofotografia.it\/\">personalmente<\/a> apprezzo di pi\u00f9 \u00e8 quello con i <strong>formaggi stagionati<\/strong>. Sebbene anche con i prodotti caseari pi\u00f9 freschi leghi altrettanto bene, quelli dalla maggiore stagionatura conservano sempre un posto d\u2019onore nella mia classifica. Pecorini e caciocavalli in prima fila, il <strong>miele<\/strong> accompagna maestosamente le mie trasgressioni culinarie quando viaggio, oppure quando sento il bisogno di un momento di svago. Cibarsi, converrete, non \u00e8 pi\u00f9 solo l\u2019atto della nutrizione, \u00e8 arte.<\/p>\n\n\n\n<p>Visita il <a href=\"https:\/\/www.micheledimaurofotografia.it\/\">sito dell&#8217;autore<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"520\" src=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/rocca-roccascalegna-micheledimaurofotografia-1024x683.jpg\" alt=\"\" class=\"wp-image-520\" srcset=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/rocca-roccascalegna-micheledimaurofotografia-1024x683.jpg 1024w, https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/rocca-roccascalegna-micheledimaurofotografia-300x200.jpg 300w, https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/rocca-roccascalegna-micheledimaurofotografia-768x512.jpg 768w, https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/rocca-roccascalegna-micheledimaurofotografia.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, un crogiolo di storia raccontata dalle architetture della citt\u00e0 vecchia, su cui vegliarda si erge La Rocca.<\/p>\n","protected":false},"author":2,"featured_media":515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[48,69],"tags":[68,18,21],"class_list":["post-513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-gusto","tag-abruzzo","tag-diario-di-viaggio","tag-michele-di-mauro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roccascalegna citt\u00e0 del miele - Secret Village<\/title>\n<meta name=\"description\" content=\"Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca. Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, e citt\u00e0 del miele.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roccascalegna citt\u00e0 del miele\" \/>\n<meta property=\"og:description\" content=\"Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca. Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, e citt\u00e0 del miele.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/\" \/>\n<meta property=\"og:site_name\" content=\"Secret Village\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T11:02:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T11:56:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/miele-michele-di-mauro-fotografia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michele Di Mauro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele Di Mauro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/\"},\"author\":{\"name\":\"Michele Di Mauro\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/person\\\/9f3e6ce7ab022e7474d37be9895cbab0\"},\"headline\":\"Roccascalegna citt\u00e0 del miele\",\"datePublished\":\"2024-04-05T11:02:47+00:00\",\"dateModified\":\"2024-11-05T11:56:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/miele-michele-di-mauro-fotografia.jpg\",\"keywords\":[\"abruzzo\",\"diario di viaggio\",\"michele di mauro\"],\"articleSection\":[\"Cultura\",\"Gusto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/\",\"name\":\"Roccascalegna citt\u00e0 del miele - Secret Village\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/miele-michele-di-mauro-fotografia.jpg\",\"datePublished\":\"2024-04-05T11:02:47+00:00\",\"dateModified\":\"2024-11-05T11:56:52+00:00\",\"description\":\"Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca. Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, e citt\u00e0 del miele.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/miele-michele-di-mauro-fotografia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/miele-michele-di-mauro-fotografia.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/cultura\\\/roccascalegna-citta-del-miele\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roccascalegna citt\u00e0 del miele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/\",\"name\":\"Secret Village\",\"description\":\"L&#039;Italia che non ti aspetti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\",\"name\":\"Secret Village\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_secret_village_3.svg\",\"contentUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_secret_village_3.svg\",\"width\":350,\"height\":350,\"caption\":\"Secret Village\"},\"image\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/person\\\/9f3e6ce7ab022e7474d37be9895cbab0\",\"name\":\"Michele Di Mauro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg\",\"caption\":\"Michele Di Mauro\"},\"description\":\"Michele Di Mauro nasce nel 1986 a Putignano, citt\u00e0 del sud-est barese, ed inizia sin dalla giovane et\u00e0 la sperimentazione fotografica, per poi farne oggetto di approfondimento etico e tecnico nel periodo universitario. Negli anni di studio che hanno condotto al conseguimento della laurea in Giurisprudenza e alla professione di consulente legale, comincia ad appassionarsi alle vicende storiche del Paese, iniziando a tracciarne i contorni mediante la fotografia e la scrittura. Fotografo di reportage, nel 2019 cura la scena di \u201cSolitudine e sete\u201d, mediometraggio del regista Fedele Dalessandro, per il quale diriger\u00e0 la fotografia e scatti di scena, tra 2021 e 2024, del film \u201c2020 \u2013 L\u2019ultima primavera\u201d. Dal 2022 \u00e8 nel progetto Secret Village, curandone i contenuti testuali, fotografici, e proseguendo la scrittura di articoli. Nel 2023 \u00e8 FIOF Italian Photography Ambassador, esponendo in Albania. Il 2024 \u00e8 dato alle stampe il libro fotografico \u201cDistanti. Scatti e frammenti di spiritualit\u00e0 in tempo di Covid\u201d, ed. VivereIn.\",\"sameAs\":[\"https:\\\/\\\/www.micheledimaurofotografia.it\",\"https:\\\/\\\/www.instagram.com\\\/micheledimauro\\\/\"],\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/autore\\\/michele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roccascalegna citt\u00e0 del miele - Secret Village","description":"Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca. Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, e citt\u00e0 del miele.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/","og_locale":"it_IT","og_type":"article","og_title":"Roccascalegna citt\u00e0 del miele","og_description":"Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca. Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, e citt\u00e0 del miele.","og_url":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/","og_site_name":"Secret Village","article_published_time":"2024-04-05T11:02:47+00:00","article_modified_time":"2024-11-05T11:56:52+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/miele-michele-di-mauro-fotografia.jpg","type":"image\/jpeg"}],"author":"Michele Di Mauro","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Michele Di Mauro","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#article","isPartOf":{"@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/"},"author":{"name":"Michele Di Mauro","@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/person\/9f3e6ce7ab022e7474d37be9895cbab0"},"headline":"Roccascalegna citt\u00e0 del miele","datePublished":"2024-04-05T11:02:47+00:00","dateModified":"2024-11-05T11:56:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/www.secretvillage.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/miele-michele-di-mauro-fotografia.jpg","keywords":["abruzzo","diario di viaggio","michele di mauro"],"articleSection":["Cultura","Gusto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.secretvillage.it\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/","url":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/","name":"Roccascalegna citt\u00e0 del miele - Secret Village","isPartOf":{"@id":"https:\/\/www.secretvillage.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#primaryimage"},"image":{"@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/miele-michele-di-mauro-fotografia.jpg","datePublished":"2024-04-05T11:02:47+00:00","dateModified":"2024-11-05T11:56:52+00:00","description":"Roccascalegna citt\u00e0 del miele all\u2019ombra della Rocca. Il borgo abruzzese \u00e8 uno dei luoghi pi\u00f9 caratteristici della regione, e citt\u00e0 del miele.","breadcrumb":{"@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#primaryimage","url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/miele-michele-di-mauro-fotografia.jpg","contentUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/04\/miele-michele-di-mauro-fotografia.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/www.secretvillage.it\/blog\/cultura\/roccascalegna-citta-del-miele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secretvillage.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Roccascalegna citt\u00e0 del miele"}]},{"@type":"WebSite","@id":"https:\/\/www.secretvillage.it\/blog\/#website","url":"https:\/\/www.secretvillage.it\/blog\/","name":"Secret Village","description":"L&#039;Italia che non ti aspetti","publisher":{"@id":"https:\/\/www.secretvillage.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secretvillage.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secretvillage.it\/blog\/#organization","name":"Secret Village","url":"https:\/\/www.secretvillage.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/logo_secret_village_3.svg","contentUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/logo_secret_village_3.svg","width":350,"height":350,"caption":"Secret Village"},"image":{"@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/person\/9f3e6ce7ab022e7474d37be9895cbab0","name":"Michele Di Mauro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg","url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg","contentUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg","caption":"Michele Di Mauro"},"description":"Michele Di Mauro nasce nel 1986 a Putignano, citt\u00e0 del sud-est barese, ed inizia sin dalla giovane et\u00e0 la sperimentazione fotografica, per poi farne oggetto di approfondimento etico e tecnico nel periodo universitario. Negli anni di studio che hanno condotto al conseguimento della laurea in Giurisprudenza e alla professione di consulente legale, comincia ad appassionarsi alle vicende storiche del Paese, iniziando a tracciarne i contorni mediante la fotografia e la scrittura. Fotografo di reportage, nel 2019 cura la scena di \u201cSolitudine e sete\u201d, mediometraggio del regista Fedele Dalessandro, per il quale diriger\u00e0 la fotografia e scatti di scena, tra 2021 e 2024, del film \u201c2020 \u2013 L\u2019ultima primavera\u201d. Dal 2022 \u00e8 nel progetto Secret Village, curandone i contenuti testuali, fotografici, e proseguendo la scrittura di articoli. Nel 2023 \u00e8 FIOF Italian Photography Ambassador, esponendo in Albania. Il 2024 \u00e8 dato alle stampe il libro fotografico \u201cDistanti. Scatti e frammenti di spiritualit\u00e0 in tempo di Covid\u201d, ed. VivereIn.","sameAs":["https:\/\/www.micheledimaurofotografia.it","https:\/\/www.instagram.com\/micheledimauro\/"],"url":"https:\/\/www.secretvillage.it\/blog\/autore\/michele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":2,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"predecessor-version":[{"id":1072,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts\/513\/revisions\/1072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/media\/515"}],"wp:attachment":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/tags?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}