{"id":1127,"date":"2024-11-10T12:16:41","date_gmt":"2024-11-10T11:16:41","guid":{"rendered":"https:\/\/www.secretvillage.it\/blog\/?p=1127"},"modified":"2024-11-18T22:40:56","modified_gmt":"2024-11-18T21:40:56","slug":"eremo-san-bartolomeo-in-legio","status":"publish","type":"post","link":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/","title":{"rendered":"Visita all&#8217;Eremo di San Bartolomeo in Legio"},"content":{"rendered":"\n<p><strong>Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. <\/strong>In un angolo di incantevole Abruzzo, a riparo dalla frenesia quotidiana e dall\u2019inquinamento, \u00e8 situato un antico rifugio, un luogo dove pace e natura sono avvolgenti. Nel cuore della Maiella, a <strong><a href=\"https:\/\/www.secretvillage.it\/comuni\/roccamorice\" target=\"_blank\" rel=\"noreferrer noopener\">Roccamorice<\/a><\/strong>, il romitorio ospit\u00f2 Pietro da Morrone, passato alla storia come <strong>Celestino V<\/strong>, Papa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-eremo-di-san-bartolomeo-in-legio-la-storia\">Eremo di San Bartolomeo in Legio, la storia<\/h2>\n\n\n\n<p>L\u2019ambiente incontaminato che circonda l\u2019eremo \u00e8 mozzafiato, eppure, non \u00e8 meno intrigante della sua storia. La grotta dove sorge la struttura, inserita nel costone calcareo e perfettamente fusa con la roccia, ospitava l\u2019uomo gi\u00e0 da tempo ben risalente ed il <strong>futuro Papa<\/strong>, in cerca di un luogo dove praticare l\u2019ascesi e ritirarsi in preghiera, oper\u00f2 un restauro del romitorio. Qui, egli si dedic\u00f2 ad una vita religiosa, in costante dialogo con la propria interiorit\u00e0.<br>La costruzione originaria \u00e8 ritenuta precedente all\u2019anno Mille, ma solo nella seconda met\u00e0 del Milleduecento Pietro da Morrone si stabilir\u00e0 tra i monti abruzzesi, vivendo due anni nell\u2019<strong>Eremo di San Bartolomeo in Legio<\/strong>. Il futuro Celestino V, infatti, di rientro dal viaggio compiuto per dare vita alla sua congrega, si concesse un periodo di profonda meditazione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-visita-all-eremo\">Visita all&#8217;eremo<\/h2>\n\n\n\n<p>Il percorso si snoda attraverso una zona del <strong><a href=\"https:\/\/www.secretvillage.it\/luoghi\/parco-nazionale-majella\" target=\"_blank\" rel=\"noreferrer noopener\">Parco Nazionale della Maiella<\/a><\/strong> dalle tinte intense, qui la natura non ha padroni e prospera nel rispetto che le si deve. La visita dell\u2019Eremo di San Bartolomeo in Legio \u00e8 un\u2019attivit\u00e0 che richiede scarpe buone, il <strong>sentiero \u00e8 facilmente percorribile sino alla met\u00e0<\/strong>, poi si fa pi\u00f9 impegnativo. Si tratta di un <strong>tragitto non faticoso<\/strong>, ma che va affrontato con attenzione, specie nelle battute finali, quando la discesa si fa pi\u00f9 ripida ed \u00e8 necessario mantenere la giusta concentrazione tra gli scalini rocciosi. La via \u00e8 ben tracciata, non si corre il rischio di perdersi, ma in condizioni di forte umidit\u00e0 o pioggia, \u00e8 bene prestare attenzione ai (pochi) punti scivolosi.<\/p>\n\n\n\n<p>L\u2019<strong>eremo celestiniano<\/strong> \u00e8 una piccola quanto accogliente costruzione, la cui semplicit\u00e0 sin da subito chiarisce la propria vocazione. Il <strong>rifugio spirituale<\/strong> affascina e cala in un\u2019<strong>ambiente di vera serenit\u00e0<\/strong>, tutt\u2019attorno lo sfondo naturale non lascia intravedere la mano dell\u2019uomo, cos\u00ec lo sguardo si libera e la mente con esso. Nei pochi metri dell\u2019interno, composto dalla cappella e da due brevi locali dove dimorare, l\u2019aria si fa densa di una pacifica concentrazione, che invoglia a <strong>svuotare l\u2019hard disk interiore<\/strong>, favorendo una concreta <strong>riconciliazione con natura ed \u201cio\u201d<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-san-bartolomeo-in-legio-l-eremo-di-roccamorice\">San Bartolomeo in Legio, l&#8217;eremo di Roccamorice<\/h3>\n\n\n\n<p>La chiesetta \u00e8 in parte ricavata dallo scavo nella roccia e le sue forme sono semplici, misura nemmeno otto metri di lunghezza e circa la met\u00e0 si apre in larghezza, giusto quel che serve per occupare la balconata che si estende nella parete calcarea. La vista da entrambi i lati dell\u2019affaccio lapideo \u00e8 mozzafiato, l\u2019<strong>Appennino Abruzzese<\/strong> con i suoi colori e la flora inalterata rapisce l\u2019occhio e strega l\u2019anima.<\/p>\n\n\n\n<p>L\u2019eremo si raggiunge da alcune diverse scalinate, una delle quali porta ad attraversare un suggestivo cunicolo nella pietra, ed a prima occhiata lascia un sorriso di benessere sul volto; la facciata reca tracce di affreschi, tre scene di cui sono leggibili solo parzialmente due. Quella centrale rappresenta un <strong>Cristo Pantocratore<\/strong>, benedicente verso il pellegrino che sta per varcarne la soglia. La chiesa ospita un <strong>dipinto di San Bartolomeo<\/strong>, a cui \u00e8 dedicata, con una particolarit\u00e0: il Santo \u00e8 raffigurato con un pugnale nella mano. L\u2019iconografia riporta la circostanza della morte dell\u2019Apostolo, che sub\u00ec il martirio e lo scorticamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-tra-le-rocce-della-maiella\">Tra le rocce della Maiella<\/h3>\n\n\n\n<p>Il mosaico paesaggistico del <a href=\"https:\/\/www.secretvillage.it\/luoghi\/parco-nazionale-majella\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Parco nazionale della Maiella<\/strong><\/a> spazia dai boschi alle piane di prato alpino, dalle vallate alle cime che nelle stagioni fredde si coprono di vellutata neve. E\u2019 una festa di colori appenninici, che durante primavera ed autunno si caratterizzano per la natura che rivive e per le tinte tra giallo, rosso ed arancio degli alberi. L\u2019inverno <strong>tra le rocce della Maiella<\/strong> \u00e8 rigido, ma regala sensazioni che non si dimenticano, mentre l\u2019estate consente un maggiore accesso alle alture.<\/p>\n\n\n\n<p>Il parco, istituito all\u2019inizio degli anni Novanta del Novecento, <strong>abbraccia i territori d\u2019Abruzzo<\/strong> che si estendono tra le province di Pescara, L\u2019Aquila e Chieti. Le terre che lo compongono sono magnifiche, l\u2019ambiente \u00e8 ricco di biodiversit\u00e0 da tutelare e per questo sono state inserite alcune riserve naturali, per preservarne la magnificenza, dalla <strong>maestosit\u00e0 montana<\/strong> al fascino delle valli.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-uomo-e-natura-parte-ii-diario-di-viaggio\">Uomo e Natura, parte II &#8211; <a href=\"https:\/\/www.micheledimaurofotografia.it\/blog-pensiero-riflessioni\/\" target=\"_blank\" rel=\"noreferrer noopener\">Diario di Viaggio<\/a><\/h2>\n\n\n\n<p>&#8220;<em>In effetti, <strong>quello tra uomo e natura \u00e8 un abbraccio senza tempo<\/strong>, antico, la natura accoglie, l\u2019uomo si evolve. Ci\u00f2 che da un lato pone grossi interrogativi \u00e8 l\u2019attuale andamento del rapporto, non appare pi\u00f9 alla pari, c\u2019\u00e8 scontro, sopraffazione. Nelle fotografie di sessanta, settant\u2019anni fa si osserva un binomio gi\u00e0 spostato verso la presenza umana invasiva, ma c\u2019\u00e8 una sostanziale convivenza pacifica, mediamente. Certo, fabbriche e opifici hanno deturpato alcuni angoli di paradiso, ma questo pu\u00f2 valere anche per i castelli del Medioevo.<\/em><\/p>\n\n\n\n<p><em>Negli scatti di <strong>Bresson<\/strong>, di <strong>Berengo Gardin<\/strong>, di <strong>Salgado<\/strong>, solo per esemplificare, si percepisce un\u2019attenzione al mondo che circonda la vita umana, che tende al predominio in alcuni casi, mentre in altri \u00e8 in simbiosi. In alcune fotografie di <strong>Dorothea Lange<\/strong>, la natura \u00e8 sullo sfondo e pare un contorno dell\u2019esistenza, quasi solo un fondale. In ci\u00f2, si intende il passaggio dalla ricerca dell\u2019armonia con la natura al confino della natura al ruolo di fattore da sfruttare al meglio.<\/em><\/p>\n\n\n\n<p><em>L\u2019amore, la contemplazione della natura nelle <strong>fotografie di Ansel Adams<\/strong>, l\u2019idea di natura che ispira e si fa musa, oggi \u00e8 forse anacronistico, malinconicamente crepuscolare, appartiene ad un\u2019altra era. Uso e consumo dell\u2019ambiente, se mi si passa la locuzione.<\/em>&#8220;. Continua a <a href=\"https:\/\/www.micheledimaurofotografia.it\/rapporto-uomo-natura-contrasto\/\" target=\"_blank\" rel=\"noreferrer noopener\">leggere l&#8217;articolo<\/a><\/p>\n\n\n\n<p>Leggi altri <a href=\"https:\/\/www.secretvillage.it\/blog\/autore\/michele\/\" target=\"_blank\" rel=\"noreferrer noopener\">articoli dell&#8217;Autore<\/a><br>Visita il <a href=\"https:\/\/www.micheledimaurofotografia.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">sito dell&#8217;Autore<\/a><\/p>\n\n\n<style>.uid-2c1b764694a756e2  .gt3pg-isotope-item {\n\tpadding-right: 20px;\n\tpadding-bottom: 20px;\n}\n.uid-2c1b764694a756e2  .gallery-isotope-wrapper {\n\tmargin-right: -20px;\n\tmargin-bottom: -20px;\n}\n<\/style><div id=\"uid-2c1b764694a756e2\" data-gt3pg-block=\"grid\" data-index=\"1\" class=\"gt3-photo-gallery-pro--isotope_gallery uid-2c1b764694a756e2 gt3pg-pro--wrapper gt3pg-pro--grid \">\t\t<div data-cols=\"2\" data-cols-tablet=\"2\" data-cols-mobile=\"2\" class=\"gt3pg-isotope-gallery columns-2 hover-default gallery-grid  corner-standard square\" data-settings=\"{&quot;id&quot;:1,&quot;uid&quot;:&quot;uid-2c1b764694a756e2&quot;,&quot;grid_type&quot;:&quot;square&quot;,&quot;modules&quot;:[&quot;Lightbox&quot;],&quot;lightboxArray&quot;:[{&quot;href&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo.jpg&quot;,&quot;title&quot;:&quot;Interno dell&#039;Eremo di Roccamorice Foto: Michele Di Mauro&quot;,&quot;thumbnail&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-150x150.jpg&quot;,&quot;description&quot;:&quot;Interno dell&#039;Eremo di Roccamorice\\nFoto: Michele Di Mauro&quot;,&quot;is_video&quot;:0,&quot;image_id&quot;:1131,&quot;width&quot;:1000,&quot;height&quot;:667},{&quot;href&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro.jpg&quot;,&quot;title&quot;:&quot;Sentiero per l&#039;Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro&quot;,&quot;thumbnail&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-150x150.jpg&quot;,&quot;description&quot;:&quot;Sentiero per l&#039;Eremo di San Bartolomeo in Legio\\nFoto: Michele Di Mauro&quot;,&quot;is_video&quot;:0,&quot;image_id&quot;:1129,&quot;width&quot;:1000,&quot;height&quot;:667}],&quot;lightbox&quot;:{&quot;enable&quot;:true,&quot;options&quot;:{&quot;instance&quot;:1}},&quot;items&quot;:[{&quot;href&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo.jpg&quot;,&quot;title&quot;:&quot;Interno dell&#039;Eremo di Roccamorice Foto: Michele Di Mauro&quot;,&quot;thumbnail&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-150x150.jpg&quot;,&quot;description&quot;:&quot;Interno dell&#039;Eremo di Roccamorice\\nFoto: Michele Di Mauro&quot;,&quot;is_video&quot;:0,&quot;image_id&quot;:1131,&quot;width&quot;:1000,&quot;height&quot;:667},{&quot;href&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro.jpg&quot;,&quot;title&quot;:&quot;Sentiero per l&#039;Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro&quot;,&quot;thumbnail&quot;:&quot;https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-150x150.jpg&quot;,&quot;description&quot;:&quot;Sentiero per l&#039;Eremo di San Bartolomeo in Legio\\nFoto: Michele Di Mauro&quot;,&quot;is_video&quot;:0,&quot;image_id&quot;:1129,&quot;width&quot;:1000,&quot;height&quot;:667}]}\">\r\n\t\t\t<div class=\"gallery-isotope-wrapper\">\r\n\t\t\t\t<div class=\"gt3pg-isotope-item loading \"  title=\"Interno dell&#039;Eremo di Roccamorice Foto: Michele Di Mauro\"><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-768x512.jpg\" class=\"gt3pg-lightbox\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper has_text_info\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-768x512.jpg\" class=\"skip-lazy gt3-lazy-image\" alt=\"Interno dell&#039;Eremo di Roccamorice Foto: Michele Di Mauro\" data-lazy-srcset=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-768x512.jpg 768w, https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-300x200.jpg 300w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-768x512.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAE0AAAAzCAYAAADSIYUBAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAJklEQVRo3u3BgQAAAADDoPlTX+AIVQEAAAAAAAAAAAAAAAAAAHAMPY8AAQeL\/AcAAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><div class=\"text_info_wrapper\"><div class=\"text_wrap_title\"><span class=\"title\">Interno dell&#039;Eremo di Roccamorice Foto: Michele Di Mauro<\/span><\/div><\/div><\/div><div class=\"gt3pg-isotope-item loading \"  title=\"Sentiero per l&#039;Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro\"><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-768x512.jpg\" class=\"gt3pg-lightbox\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper has_text_info\"><img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-768x512.jpg\" class=\"skip-lazy gt3-lazy-image\" alt=\"Sentiero per l&#039;Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro\" data-lazy-srcset=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-768x512.jpg 768w, https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-300x200.jpg 300w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-768x512.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAE0AAAAzCAYAAADSIYUBAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAJklEQVRo3u3BgQAAAADDoPlTX+AIVQEAAAAAAAAAAAAAAAAAAHAMPY8AAQeL\/AcAAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><div class=\"text_info_wrapper\"><div class=\"text_wrap_title\"><span class=\"title\">Sentiero per l&#039;Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro<\/span><\/div><\/div><\/div>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<script type=\"application\/json\" id=\"settings--uid-2c1b764694a756e2\">{\"id\":1,\"uid\":\"uid-2c1b764694a756e2\",\"grid_type\":\"square\",\"modules\":[\"Lightbox\"],\"lightboxArray\":[{\"href\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo.jpg\",\"title\":\"Interno dell'Eremo di Roccamorice Foto: Michele Di Mauro\",\"thumbnail\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-150x150.jpg\",\"description\":\"Interno dell'Eremo di Roccamorice\\nFoto: Michele Di Mauro\",\"is_video\":0,\"image_id\":1131,\"width\":1000,\"height\":667},{\"href\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro.jpg\",\"title\":\"Sentiero per l'Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro\",\"thumbnail\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-150x150.jpg\",\"description\":\"Sentiero per l'Eremo di San Bartolomeo in Legio\\nFoto: Michele Di Mauro\",\"is_video\":0,\"image_id\":1129,\"width\":1000,\"height\":667}],\"lightbox\":{\"enable\":true,\"options\":{\"instance\":1}},\"items\":[{\"href\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo.jpg\",\"title\":\"Interno dell'Eremo di Roccamorice Foto: Michele Di Mauro\",\"thumbnail\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village-abruzzo-150x150.jpg\",\"description\":\"Interno dell'Eremo di Roccamorice\\nFoto: Michele Di Mauro\",\"is_video\":0,\"image_id\":1131,\"width\":1000,\"height\":667},{\"href\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro.jpg\",\"title\":\"Sentiero per l'Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro\",\"thumbnail\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-150x150.jpg\",\"description\":\"Sentiero per l'Eremo di San Bartolomeo in Legio\\nFoto: Michele Di Mauro\",\"is_video\":0,\"image_id\":1129,\"width\":1000,\"height\":667}]}<\/script>\r\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Viaggio tra le rocce del Parco nazionale della Maiella, alla scoperta dell&#8217;Eremo di San Bartolomeo in Legio, nel territorio di Roccamorice.<\/p>\n","protected":false},"author":2,"featured_media":1130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[20],"tags":[68,18,28],"class_list":["post-1127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-di-viaggio","tag-abruzzo","tag-diario-di-viaggio","tag-michele-di-mauro-fotografia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Visita all&#039;Eremo di San Bartolomeo in Legio - Secret Village<\/title>\n<meta name=\"description\" content=\"Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. A Roccamorice, un&#039;esperienza straordinaria tra storia e natura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita all&#039;Eremo di San Bartolomeo in Legio\" \/>\n<meta property=\"og:description\" content=\"Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. A Roccamorice, un&#039;esperienza straordinaria tra storia e natura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/\" \/>\n<meta property=\"og:site_name\" content=\"Secret Village\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-10T11:16:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T21:40:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michele Di Mauro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele Di Mauro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/\"},\"author\":{\"name\":\"Michele Di Mauro\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/person\\\/9f3e6ce7ab022e7474d37be9895cbab0\"},\"headline\":\"Visita all&#8217;Eremo di San Bartolomeo in Legio\",\"datePublished\":\"2024-11-10T11:16:41+00:00\",\"dateModified\":\"2024-11-18T21:40:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/\"},\"wordCount\":975,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg\",\"keywords\":[\"abruzzo\",\"diario di viaggio\",\"michele di mauro fotografia\"],\"articleSection\":[\"Diario di viaggio\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/\",\"name\":\"Visita all'Eremo di San Bartolomeo in Legio - Secret Village\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg\",\"datePublished\":\"2024-11-10T11:16:41+00:00\",\"dateModified\":\"2024-11-18T21:40:56+00:00\",\"description\":\"Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. A Roccamorice, un'esperienza straordinaria tra storia e natura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg\",\"contentUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Facciata Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/diario-di-viaggio\\\/eremo-san-bartolomeo-in-legio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visita all&#8217;Eremo di San Bartolomeo in Legio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/\",\"name\":\"Secret Village\",\"description\":\"L&#039;Italia che non ti aspetti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#organization\",\"name\":\"Secret Village\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_secret_village_3.svg\",\"contentUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_secret_village_3.svg\",\"width\":350,\"height\":350,\"caption\":\"Secret Village\"},\"image\":{\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/#\\\/schema\\\/person\\\/9f3e6ce7ab022e7474d37be9895cbab0\",\"name\":\"Michele Di Mauro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg\",\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg\",\"caption\":\"Michele Di Mauro\"},\"description\":\"Michele Di Mauro nasce nel 1986 a Putignano, citt\u00e0 del sud-est barese, ed inizia sin dalla giovane et\u00e0 la sperimentazione fotografica, per poi farne oggetto di approfondimento etico e tecnico nel periodo universitario. Negli anni di studio che hanno condotto al conseguimento della laurea in Giurisprudenza e alla professione di consulente legale, comincia ad appassionarsi alle vicende storiche del Paese, iniziando a tracciarne i contorni mediante la fotografia e la scrittura. Fotografo di reportage, nel 2019 cura la scena di \u201cSolitudine e sete\u201d, mediometraggio del regista Fedele Dalessandro, per il quale diriger\u00e0 la fotografia e scatti di scena, tra 2021 e 2024, del film \u201c2020 \u2013 L\u2019ultima primavera\u201d. Dal 2022 \u00e8 nel progetto Secret Village, curandone i contenuti testuali, fotografici, e proseguendo la scrittura di articoli. Nel 2023 \u00e8 FIOF Italian Photography Ambassador, esponendo in Albania. Il 2024 \u00e8 dato alle stampe il libro fotografico \u201cDistanti. Scatti e frammenti di spiritualit\u00e0 in tempo di Covid\u201d, ed. VivereIn.\",\"sameAs\":[\"https:\\\/\\\/www.micheledimaurofotografia.it\",\"https:\\\/\\\/www.instagram.com\\\/micheledimauro\\\/\"],\"url\":\"https:\\\/\\\/www.secretvillage.it\\\/blog\\\/autore\\\/michele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Visita all'Eremo di San Bartolomeo in Legio - Secret Village","description":"Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. A Roccamorice, un'esperienza straordinaria tra storia e natura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/","og_locale":"it_IT","og_type":"article","og_title":"Visita all'Eremo di San Bartolomeo in Legio","og_description":"Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. A Roccamorice, un'esperienza straordinaria tra storia e natura.","og_url":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/","og_site_name":"Secret Village","article_published_time":"2024-11-10T11:16:41+00:00","article_modified_time":"2024-11-18T21:40:56+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg","type":"image\/jpeg"}],"author":"Michele Di Mauro","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Michele Di Mauro","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#article","isPartOf":{"@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/"},"author":{"name":"Michele Di Mauro","@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/person\/9f3e6ce7ab022e7474d37be9895cbab0"},"headline":"Visita all&#8217;Eremo di San Bartolomeo in Legio","datePublished":"2024-11-10T11:16:41+00:00","dateModified":"2024-11-18T21:40:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/"},"wordCount":975,"commentCount":0,"publisher":{"@id":"https:\/\/www.secretvillage.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg","keywords":["abruzzo","diario di viaggio","michele di mauro fotografia"],"articleSection":["Diario di viaggio"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.secretvillage.it\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/","url":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/","name":"Visita all'Eremo di San Bartolomeo in Legio - Secret Village","isPartOf":{"@id":"https:\/\/www.secretvillage.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#primaryimage"},"image":{"@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg","datePublished":"2024-11-10T11:16:41+00:00","dateModified":"2024-11-18T21:40:56+00:00","description":"Visita all\u2019Eremo di San Bartolomeo in Legio, tra le rocce della Maiella. A Roccamorice, un'esperienza straordinaria tra storia e natura.","breadcrumb":{"@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#primaryimage","url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg","contentUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/11\/eremo-san-bartolomeo-in-legio-roccamorice-michele-di-mauro-fotografia-secret-village.jpg","width":1000,"height":667,"caption":"Facciata Eremo di San Bartolomeo in Legio Foto: Michele Di Mauro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.secretvillage.it\/blog\/diario-di-viaggio\/eremo-san-bartolomeo-in-legio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.secretvillage.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Visita all&#8217;Eremo di San Bartolomeo in Legio"}]},{"@type":"WebSite","@id":"https:\/\/www.secretvillage.it\/blog\/#website","url":"https:\/\/www.secretvillage.it\/blog\/","name":"Secret Village","description":"L&#039;Italia che non ti aspetti","publisher":{"@id":"https:\/\/www.secretvillage.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.secretvillage.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.secretvillage.it\/blog\/#organization","name":"Secret Village","url":"https:\/\/www.secretvillage.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/logo_secret_village_3.svg","contentUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/logo_secret_village_3.svg","width":350,"height":350,"caption":"Secret Village"},"image":{"@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.secretvillage.it\/blog\/#\/schema\/person\/9f3e6ce7ab022e7474d37be9895cbab0","name":"Michele Di Mauro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg","url":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg","contentUrl":"https:\/\/www.secretvillage.it\/blog\/wp-content\/uploads\/2024\/03\/michele-di-mauro-fotografia-profilo-secret-village-150x150.jpg","caption":"Michele Di Mauro"},"description":"Michele Di Mauro nasce nel 1986 a Putignano, citt\u00e0 del sud-est barese, ed inizia sin dalla giovane et\u00e0 la sperimentazione fotografica, per poi farne oggetto di approfondimento etico e tecnico nel periodo universitario. Negli anni di studio che hanno condotto al conseguimento della laurea in Giurisprudenza e alla professione di consulente legale, comincia ad appassionarsi alle vicende storiche del Paese, iniziando a tracciarne i contorni mediante la fotografia e la scrittura. Fotografo di reportage, nel 2019 cura la scena di \u201cSolitudine e sete\u201d, mediometraggio del regista Fedele Dalessandro, per il quale diriger\u00e0 la fotografia e scatti di scena, tra 2021 e 2024, del film \u201c2020 \u2013 L\u2019ultima primavera\u201d. Dal 2022 \u00e8 nel progetto Secret Village, curandone i contenuti testuali, fotografici, e proseguendo la scrittura di articoli. Nel 2023 \u00e8 FIOF Italian Photography Ambassador, esponendo in Albania. Il 2024 \u00e8 dato alle stampe il libro fotografico \u201cDistanti. Scatti e frammenti di spiritualit\u00e0 in tempo di Covid\u201d, ed. VivereIn.","sameAs":["https:\/\/www.micheledimaurofotografia.it","https:\/\/www.instagram.com\/micheledimauro\/"],"url":"https:\/\/www.secretvillage.it\/blog\/autore\/michele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts\/1127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/comments?post=1127"}],"version-history":[{"count":3,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts\/1127\/revisions"}],"predecessor-version":[{"id":1150,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/posts\/1127\/revisions\/1150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/media\/1130"}],"wp:attachment":[{"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/categories?post=1127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.secretvillage.it\/blog\/wp-json\/wp\/v2\/tags?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}